{"id":7063,"date":"2024-12-05T09:41:30","date_gmt":"2024-12-05T02:41:30","guid":{"rendered":"https:\/\/magisterbiologi.uin-malang.ac.id\/?p=7063"},"modified":"2024-12-05T09:41:30","modified_gmt":"2024-12-05T02:41:30","slug":"kuliah-marine-biology","status":"publish","type":"post","link":"https:\/\/magisterbiologi.uin-malang.ac.id\/zh\/kuliah-marine-biology\/","title":{"rendered":"Kuliah Marine Biology"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Topik: Kuliah Marine Biology Laboratory<br>Waktu: 5 Des 2024 11:00 AM Jakarta<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bergabung Zoom Rapat<br>https:\/\/us06web.zoom.us\/j\/83046450836?pwd=g5PYLsIm1P8dvbAHLI4sdDgGgIXPXA.1<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">ID Rapat: 830 4645 0836<br>Kode Sandi: 526676<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\">Sekali ketuk pada ponsel<br>+16469313860,,83046450836#,,,,<em>526676# Amerika Serikat +16694449171,,83046450836#,,,,<\/em>526676# Amerika Serikat<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\">Telepon berdasarkan lokasi Anda<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>+1 646 931 3860 Amerika Serikat<\/li>\n\n\n\n<li>+1 669 444 9171 Amerika Serikat<\/li>\n\n\n\n<li>+1 689 278 1000 Amerika Serikat<\/li>\n\n\n\n<li>+1 719 359 4580 Amerika Serikat<\/li>\n\n\n\n<li>+1 720 707 2699 Amerika Serikat (Denver)<\/li>\n\n\n\n<li>+1 253 205 0468 Amerika Serikat<\/li>\n\n\n\n<li>+1 253 215 8782 Amerika Serikat (Tacoma)<\/li>\n\n\n\n<li>+1 301 715 8592 Amerika Serikat (Washington DC)<\/li>\n\n\n\n<li>+1 305 224 1968 Amerika Serikat<\/li>\n\n\n\n<li>+1 309 205 3325 Amerika Serikat<\/li>\n\n\n\n<li>+1 312 626 6799 Amerika Serikat (Chicago)<\/li>\n\n\n\n<li>+1 346 248 7799 Amerika Serikat (Houston)<\/li>\n\n\n\n<li>+1 360 209 5623 Amerika Serikat<\/li>\n\n\n\n<li>+1 386 347 5053 Amerika Serikat<\/li>\n\n\n\n<li>+1 507 473 4847 Amerika Serikat<\/li>\n\n\n\n<li>+1 564 217 2000 Amerika Serikat<\/li>\n\n\n\n<li>+1 646 558 8656 Amerika Serikat (New York)<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">ID Rapat: 830 4645 0836<br>Kode Sandi: 526676<\/p>","protected":false},"excerpt":{"rendered":"<p>Topik: Kuliah Marine Biology LaboratoryWaktu: 5 Des 2024 11:00 AM Jakarta Bergabung Zoom Rapathttps:\/\/us06web.zoom.us\/j\/83046450836?pwd=g5PYLsIm1P8dvbAHLI4sdDgGgIXPXA.1 ID Rapat: 830 4645 0836Kode Sandi: 526676 Sekali ketuk pada ponsel+16469313860,,83046450836#,,,,526676# Amerika Serikat +16694449171,,83046450836#,,,,526676# Amerika Serikat Telepon berdasarkan lokasi Anda ID Rapat: 830 4645 0836Kode Sandi: 526676<\/p>","protected":false},"author":1,"featured_media":7064,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-7063","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informasi"],"_links":{"self":[{"href":"https:\/\/magisterbiologi.uin-malang.ac.id\/zh\/wp-json\/wp\/v2\/posts\/7063","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/magisterbiologi.uin-malang.ac.id\/zh\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/magisterbiologi.uin-malang.ac.id\/zh\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/magisterbiologi.uin-malang.ac.id\/zh\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/magisterbiologi.uin-malang.ac.id\/zh\/wp-json\/wp\/v2\/comments?post=7063"}],"version-history":[{"count":0,"href":"https:\/\/magisterbiologi.uin-malang.ac.id\/zh\/wp-json\/wp\/v2\/posts\/7063\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/magisterbiologi.uin-malang.ac.id\/zh\/wp-json\/wp\/v2\/media\/7064"}],"wp:attachment":[{"href":"https:\/\/magisterbiologi.uin-malang.ac.id\/zh\/wp-json\/wp\/v2\/media?parent=7063"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/magisterbiologi.uin-malang.ac.id\/zh\/wp-json\/wp\/v2\/categories?post=7063"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/magisterbiologi.uin-malang.ac.id\/zh\/wp-json\/wp\/v2\/tags?post=7063"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}